{"id":1232,"date":"2025-07-23T19:43:49","date_gmt":"2025-07-23T17:43:49","guid":{"rendered":"https:\/\/hausarztpraxis-worb.ch\/visione-e-missione\/"},"modified":"2025-08-13T01:08:13","modified_gmt":"2025-08-12T23:08:13","slug":"visione-e-missione","status":"publish","type":"page","link":"https:\/\/hausarztpraxis-worb.ch\/it\/visione-e-missione\/","title":{"rendered":"Visione e missione"},"content":{"rendered":"\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-bottom:60px\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">La nostra visione: <strong>\u201cUn vantaggio per le persone e la regione\u201d.<\/strong><br\/>Stabiliamo nuovi standard nell\u2019assistenza medica di base e nella medicina d\u2019urgenza \u2013 con competenza, empatia e metodi di trattamento moderni.<br\/><strong>Il nostro plus: medicina con cuore, mente e futuro<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La nostra missione<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siamo appassionati ed <strong>entusiasti<\/strong> di fornire <strong>assistenza<\/strong> medica di base. I nostri pazienti sono al centro del nostro lavoro: li trattiamo con <strong>gentilezza<\/strong>, <strong>rispetto<\/strong> e <strong>riconoscenza<\/strong>. Per noi \u00e8 un privilegio essere al fianco delle persone che si <strong>affidano<\/strong> a noi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In quanto studio familiare, attribuiamo grande importanza a un&#8217;<strong>atmosfera<\/strong> <strong>calda<\/strong> e <strong>positiva<\/strong>, sia nei rapporti con i pazienti che all&#8217;interno del nostro team. <strong>Rispetto<\/strong>, <strong>fiducia<\/strong> e <strong>apprezzamento<\/strong> sono alla base della nostra collaborazione. Anche nei momenti difficili, restiamo uniti e ci <strong>sosteniamo<\/strong> a vicenda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I nostri <strong>dipendenti<\/strong> sono il nostro <strong>bene pi\u00f9 prezioso<\/strong>. <strong>Promuoviamo il<\/strong> loro <strong>sviluppo<\/strong> individuale, <strong>sosteniamo la<\/strong> formazione continua e creiamo un ambiente in cui i <strong>talenti<\/strong> e i <strong>punti di forza<\/strong> possano essere sviluppati in modo mirato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ci concentriamo sul massimo livello di <strong>professionalit\u00e0<\/strong> e <strong>competenza<\/strong>. Integriamo le ultime scoperte mediche nel nostro lavoro quotidiano attraverso una formazione continua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;apertura all&#8217;<strong>innovazione <\/strong>e al <strong>progresso<\/strong> \u00e8 importante per noi. Apprezziamo le buone idee e le <strong>innovazioni<\/strong> sensate per rendere il nostro studio moderno e orientato al futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il nostro obiettivo \u00e8 quello di dare un contributo significativo all&#8217;assistenza medica di base nella regione. <strong>Sviluppando<\/strong> continuamente i nostri servizi, garantiamo un&#8217;assistenza completa e di alta qualit\u00e0 agli abitanti di Worb.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La nostra visione: \u201cUn vantaggio per le persone e la regione\u201d.Stabiliamo nuovi standard nell\u2019assistenza medica di base e nella medicina d\u2019urgenza \u2013 con competenza, empatia e metodi di trattamento moderni.Il nostro plus: medicina con cuore, mente e futuro La nostra missione Siamo appassionati ed entusiasti di fornire assistenza medica di base. I nostri pazienti sono [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":582,"parent":0,"menu_order":76,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1232","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/hausarztpraxis-worb.ch\/it\/wp-json\/wp\/v2\/pages\/1232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hausarztpraxis-worb.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hausarztpraxis-worb.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hausarztpraxis-worb.ch\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/hausarztpraxis-worb.ch\/it\/wp-json\/wp\/v2\/comments?post=1232"}],"version-history":[{"count":1,"href":"https:\/\/hausarztpraxis-worb.ch\/it\/wp-json\/wp\/v2\/pages\/1232\/revisions"}],"predecessor-version":[{"id":1233,"href":"https:\/\/hausarztpraxis-worb.ch\/it\/wp-json\/wp\/v2\/pages\/1232\/revisions\/1233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hausarztpraxis-worb.ch\/it\/wp-json\/wp\/v2\/media\/582"}],"wp:attachment":[{"href":"https:\/\/hausarztpraxis-worb.ch\/it\/wp-json\/wp\/v2\/media?parent=1232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}