{"id":1494,"date":"2025-07-23T23:20:41","date_gmt":"2025-07-23T21:20:41","guid":{"rendered":"https:\/\/hausarztpraxis-worb.ch\/team\/dra-doris-von-muralt\/"},"modified":"2026-02-02T19:14:29","modified_gmt":"2026-02-02T18:14:29","slug":"dra-doris-von-muralt","status":"publish","type":"team","link":"https:\/\/hausarztpraxis-worb.ch\/es\/team\/dra-doris-von-muralt\/","title":{"rendered":"Dra. Doris von Muralt"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abSoy un m\u00e9dico apasionado y me comprometo con mis pacientes con mucho amor y entusiasmo\u00bb.<\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\">La Sra. von Muralt termin\u00f3 sus estudios de Medicina en 1981 con el examen estatal. A continuaci\u00f3n trabaj\u00f3 durante un a\u00f1o en cirug\u00eda visceral en el Inselspital de Berna, antes de trasladarse al Hospital Universitario de Z\u00farich, donde se especializ\u00f3 en medicina nuclear y radioterapia. De 1984 a 1987, continu\u00f3 su formaci\u00f3n ginecol\u00f3gica en el Hospital Universitario de Z\u00farich y en el Hospital de Zug. Finalmente, regres\u00f3 al Inselspital de Berna y trabaj\u00f3 en anestesiolog\u00eda y cuidados intensivos de 1987 a 1988. Tras dos a\u00f1os m\u00e1s en medicina interna en el Hospital de Thun, finalmente abri\u00f3 su propia consulta en Worb en abril de 1990.<br\/>La Dra. von Muralt dirigi\u00f3 y gestion\u00f3 con \u00e9xito la consulta de Worb como propietaria desde 1990 hasta 2022. Durante este tiempo, puso una importante piedra angular para la actual consulta de Worb y contribuy\u00f3 significativamente a su desarrollo y \u00e9xito.     <\/p>\n\n<p class=\"wp-block-paragraph\">La Dra. von Muralt es una doctora apasionada que sigue atendiendo a sus pacientes con gran amor y entusiasmo.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Cualificaciones<br\/><\/strong>FMH especialista en medicina generalCertificado de aptitud en laboratorio de pr\u00e1cticas KHM<br\/>Certificado de aptitud en rayos X de dosis intensiva<br\/>M\u00e9dico docente en el Instituto de Medicina Familiar de Berna (BIHAM)<br\/>M\u00e9dico escolar del municipio de Worb<br\/>Oficial m\u00e9dico de las autoridades de tr\u00e1fico para los niveles 1 y 2<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Afiliaciones<br\/><\/strong>Asociaci\u00f3n M\u00e9dica Suiza FMH<br\/>Asociaci\u00f3n M\u00e9dica del Cant\u00f3n de Berna<br\/>Instituto de Medicina Familiar de Berna (BIHAM)<br\/>Red de M\u00e9dicos de Berna<\/p>\n","protected":false},"featured_media":639,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"team-category":[49],"class_list":["post-1494","team","type-team","status-publish","has-post-thumbnail","hentry","team-category-doctores"],"acf":[],"_links":{"self":[{"href":"https:\/\/hausarztpraxis-worb.ch\/es\/wp-json\/wp\/v2\/team\/1494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hausarztpraxis-worb.ch\/es\/wp-json\/wp\/v2\/team"}],"about":[{"href":"https:\/\/hausarztpraxis-worb.ch\/es\/wp-json\/wp\/v2\/types\/team"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hausarztpraxis-worb.ch\/es\/wp-json\/wp\/v2\/media\/639"}],"wp:attachment":[{"href":"https:\/\/hausarztpraxis-worb.ch\/es\/wp-json\/wp\/v2\/media?parent=1494"}],"wp:term":[{"taxonomy":"team-category","embeddable":true,"href":"https:\/\/hausarztpraxis-worb.ch\/es\/wp-json\/wp\/v2\/team-category?post=1494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}